{"id":620,"count":1,"description":"","link":"https:\/\/ceylontimes.lk\/news\/archives\/tag\/%e0%b6%b8%e0%b7%90%e0%b6%af-%e0%b6%b4%e0%b7%99%e0%b6%bb%e0%b6%af%e0%b7%92%e0%b6%9c-%e0%b6%bd%e0%b7%8f%e0%b6%82%e0%b6%9a%e0%b7%92%e0%b6%9a%e0%b6%ba%e0%b6%b1%e0%b7%8a-%e0%b6%bb%e0%b6%9a%e0%b7%92","name":"\u0db8\u0dd0\u0daf \u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c \u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca \u0dbb\u0d9a\u0dd2\u0db1\u0dca\u0db1 \u0dc0\u0dd0\u0da9\u0db4\u0dd2\u0dc5\u0dd2\u0dc0\u0dd9\u0dbd\u0d9a\u0dca","slug":"%e0%b6%b8%e0%b7%90%e0%b6%af-%e0%b6%b4%e0%b7%99%e0%b6%bb%e0%b6%af%e0%b7%92%e0%b6%9c-%e0%b6%bd%e0%b7%8f%e0%b6%82%e0%b6%9a%e0%b7%92%e0%b6%9a%e0%b6%ba%e0%b6%b1%e0%b7%8a-%e0%b6%bb%e0%b6%9a%e0%b7%92","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0db8\u0dd0\u0daf \u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c \u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca \u0dbb\u0d9a\u0dd2\u0db1\u0dca\u0db1 \u0dc0\u0dd0\u0da9\u0db4\u0dd2\u0dc5\u0dd2\u0dc0\u0dd9\u0dbd\u0d9a\u0dca Archives - Ceylon Times | Sri Lanka Latest News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ceylontimes.lk\/news\/archives\/tag\/\u0db8\u0dd0\u0daf-\u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c-\u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca-\u0dbb\u0d9a\u0dd2\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0db8\u0dd0\u0daf \u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c \u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca \u0dbb\u0d9a\u0dd2\u0db1\u0dca\u0db1 \u0dc0\u0dd0\u0da9\u0db4\u0dd2\u0dc5\u0dd2\u0dc0\u0dd9\u0dbd\u0d9a\u0dca Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ceylontimes.lk\/news\/archives\/tag\/\u0db8\u0dd0\u0daf-\u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c-\u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca-\u0dbb\u0d9a\u0dd2\" \/>\n<meta property=\"og:site_name\" content=\"Ceylon Times | Sri Lanka Latest News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/archives\\\/tag\\\/%e0%b6%b8%e0%b7%90%e0%b6%af-%e0%b6%b4%e0%b7%99%e0%b6%bb%e0%b6%af%e0%b7%92%e0%b6%9c-%e0%b6%bd%e0%b7%8f%e0%b6%82%e0%b6%9a%e0%b7%92%e0%b6%9a%e0%b6%ba%e0%b6%b1%e0%b7%8a-%e0%b6%bb%e0%b6%9a%e0%b7%92\",\"url\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/archives\\\/tag\\\/%e0%b6%b8%e0%b7%90%e0%b6%af-%e0%b6%b4%e0%b7%99%e0%b6%bb%e0%b6%af%e0%b7%92%e0%b6%9c-%e0%b6%bd%e0%b7%8f%e0%b6%82%e0%b6%9a%e0%b7%92%e0%b6%9a%e0%b6%ba%e0%b6%b1%e0%b7%8a-%e0%b6%bb%e0%b6%9a%e0%b7%92\",\"name\":\"\u0db8\u0dd0\u0daf \u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c \u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca \u0dbb\u0d9a\u0dd2\u0db1\u0dca\u0db1 \u0dc0\u0dd0\u0da9\u0db4\u0dd2\u0dc5\u0dd2\u0dc0\u0dd9\u0dbd\u0d9a\u0dca Archives - Ceylon Times | Sri Lanka Latest News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/archives\\\/tag\\\/%e0%b6%b8%e0%b7%90%e0%b6%af-%e0%b6%b4%e0%b7%99%e0%b6%bb%e0%b6%af%e0%b7%92%e0%b6%9c-%e0%b6%bd%e0%b7%8f%e0%b6%82%e0%b6%9a%e0%b7%92%e0%b6%9a%e0%b6%ba%e0%b6%b1%e0%b7%8a-%e0%b6%bb%e0%b6%9a%e0%b7%92#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/archives\\\/tag\\\/%e0%b6%b8%e0%b7%90%e0%b6%af-%e0%b6%b4%e0%b7%99%e0%b6%bb%e0%b6%af%e0%b7%92%e0%b6%9c-%e0%b6%bd%e0%b7%8f%e0%b6%82%e0%b6%9a%e0%b7%92%e0%b6%9a%e0%b6%ba%e0%b6%b1%e0%b7%8a-%e0%b6%bb%e0%b6%9a%e0%b7%92#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0db8\u0dd0\u0daf \u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c \u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca \u0dbb\u0d9a\u0dd2\u0db1\u0dca\u0db1 \u0dc0\u0dd0\u0da9\u0db4\u0dd2\u0dc5\u0dd2\u0dc0\u0dd9\u0dbd\u0d9a\u0dca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/\",\"name\":\"Ceylon Times | Sri Lanka Latest News\",\"description\":\"Challenging Ideology\",\"publisher\":{\"@id\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/#organization\",\"name\":\"Ceylon Times | Sri Lanka Latest News\",\"url\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo@2x-300x42-1.png\",\"contentUrl\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo@2x-300x42-1.png\",\"width\":300,\"height\":42,\"caption\":\"Ceylon Times | Sri Lanka Latest News\"},\"image\":{\"@id\":\"https:\\\/\\\/ceylontimes.lk\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0db8\u0dd0\u0daf \u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c \u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca \u0dbb\u0d9a\u0dd2\u0db1\u0dca\u0db1 \u0dc0\u0dd0\u0da9\u0db4\u0dd2\u0dc5\u0dd2\u0dc0\u0dd9\u0dbd\u0d9a\u0dca Archives - Ceylon Times | Sri Lanka Latest News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ceylontimes.lk\/news\/archives\/tag\/\u0db8\u0dd0\u0daf-\u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c-\u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca-\u0dbb\u0d9a\u0dd2","og_locale":"en_US","og_type":"article","og_title":"\u0db8\u0dd0\u0daf \u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c \u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca \u0dbb\u0d9a\u0dd2\u0db1\u0dca\u0db1 \u0dc0\u0dd0\u0da9\u0db4\u0dd2\u0dc5\u0dd2\u0dc0\u0dd9\u0dbd\u0d9a\u0dca Archives","og_url":"https:\/\/ceylontimes.lk\/news\/archives\/tag\/\u0db8\u0dd0\u0daf-\u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c-\u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca-\u0dbb\u0d9a\u0dd2","og_site_name":"Ceylon Times | Sri Lanka Latest News","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ceylontimes.lk\/news\/archives\/tag\/%e0%b6%b8%e0%b7%90%e0%b6%af-%e0%b6%b4%e0%b7%99%e0%b6%bb%e0%b6%af%e0%b7%92%e0%b6%9c-%e0%b6%bd%e0%b7%8f%e0%b6%82%e0%b6%9a%e0%b7%92%e0%b6%9a%e0%b6%ba%e0%b6%b1%e0%b7%8a-%e0%b6%bb%e0%b6%9a%e0%b7%92","url":"https:\/\/ceylontimes.lk\/news\/archives\/tag\/%e0%b6%b8%e0%b7%90%e0%b6%af-%e0%b6%b4%e0%b7%99%e0%b6%bb%e0%b6%af%e0%b7%92%e0%b6%9c-%e0%b6%bd%e0%b7%8f%e0%b6%82%e0%b6%9a%e0%b7%92%e0%b6%9a%e0%b6%ba%e0%b6%b1%e0%b7%8a-%e0%b6%bb%e0%b6%9a%e0%b7%92","name":"\u0db8\u0dd0\u0daf \u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c \u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca \u0dbb\u0d9a\u0dd2\u0db1\u0dca\u0db1 \u0dc0\u0dd0\u0da9\u0db4\u0dd2\u0dc5\u0dd2\u0dc0\u0dd9\u0dbd\u0d9a\u0dca Archives - Ceylon Times | Sri Lanka Latest News","isPartOf":{"@id":"https:\/\/ceylontimes.lk\/news\/#website"},"breadcrumb":{"@id":"https:\/\/ceylontimes.lk\/news\/archives\/tag\/%e0%b6%b8%e0%b7%90%e0%b6%af-%e0%b6%b4%e0%b7%99%e0%b6%bb%e0%b6%af%e0%b7%92%e0%b6%9c-%e0%b6%bd%e0%b7%8f%e0%b6%82%e0%b6%9a%e0%b7%92%e0%b6%9a%e0%b6%ba%e0%b6%b1%e0%b7%8a-%e0%b6%bb%e0%b6%9a%e0%b7%92#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ceylontimes.lk\/news\/archives\/tag\/%e0%b6%b8%e0%b7%90%e0%b6%af-%e0%b6%b4%e0%b7%99%e0%b6%bb%e0%b6%af%e0%b7%92%e0%b6%9c-%e0%b6%bd%e0%b7%8f%e0%b6%82%e0%b6%9a%e0%b7%92%e0%b6%9a%e0%b6%ba%e0%b6%b1%e0%b7%8a-%e0%b6%bb%e0%b6%9a%e0%b7%92#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ceylontimes.lk\/news\/"},{"@type":"ListItem","position":2,"name":"\u0db8\u0dd0\u0daf \u0db4\u0dd9\u0dbb\u0daf\u0dd2\u0d9c \u0dbd\u0dcf\u0d82\u0d9a\u0dd2\u0d9a\u0dba\u0db1\u0dca \u0dbb\u0d9a\u0dd2\u0db1\u0dca\u0db1 \u0dc0\u0dd0\u0da9\u0db4\u0dd2\u0dc5\u0dd2\u0dc0\u0dd9\u0dbd\u0d9a\u0dca"}]},{"@type":"WebSite","@id":"https:\/\/ceylontimes.lk\/news\/#website","url":"https:\/\/ceylontimes.lk\/news\/","name":"Ceylon Times | Sri Lanka Latest News","description":"Challenging Ideology","publisher":{"@id":"https:\/\/ceylontimes.lk\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ceylontimes.lk\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ceylontimes.lk\/news\/#organization","name":"Ceylon Times | Sri Lanka Latest News","url":"https:\/\/ceylontimes.lk\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ceylontimes.lk\/news\/#\/schema\/logo\/image\/","url":"https:\/\/ceylontimes.lk\/news\/wp-content\/uploads\/2025\/04\/logo@2x-300x42-1.png","contentUrl":"https:\/\/ceylontimes.lk\/news\/wp-content\/uploads\/2025\/04\/logo@2x-300x42-1.png","width":300,"height":42,"caption":"Ceylon Times | Sri Lanka Latest News"},"image":{"@id":"https:\/\/ceylontimes.lk\/news\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ceylontimes.lk\/news\/wp-json\/wp\/v2\/tags\/620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceylontimes.lk\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ceylontimes.lk\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ceylontimes.lk\/news\/wp-json\/wp\/v2\/posts?tags=620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}